{"id":9883,"date":"2024-06-07T19:18:44","date_gmt":"2024-06-08T00:18:44","guid":{"rendered":"https:\/\/www.binationalwaters.org\/?p=9883"},"modified":"2025-05-07T13:43:04","modified_gmt":"2025-05-07T18:43:04","slug":"publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos","status":"publish","type":"post","link":"https:\/\/www.binationalwaters.org\/es\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/","title":{"rendered":"Publican art\u00edculo sobre est\u00e1ndares de calidad del agua fronteriza en la gesti\u00f3n de recursos h\u00eddricos"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Profesionales del sector h\u00eddrico pueden consultar el documento \u201cAcuerdo Integral de Gesti\u00f3n de la Calidad del Agua Transfronteriza con Directrices para el Desarrollo de un Plan de Gesti\u00f3n, Est\u00e1ndares y Criterios, ANSI\/ASCE\/EWRI 33-23\u201d.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Comit\u00e9 Internacional de Est\u00e1ndares de Calidad del Agua Fronteriza del Instituto de Recursos Ambientales e H\u00eddricos de ASCE, public\u00f3 el documento \u201cAcuerdo Integral de Gesti\u00f3n de la Calidad del Agua Transfronteriza con Directrices para el Desarrollo de un Plan de Gesti\u00f3n, Est\u00e1ndares y Criterios, ANSI \/ASCE\/EWRI 33-23\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de este documento se presenta un marco de referencia exhaustivo dise\u00f1ado para asistir a los gobiernos ribere\u00f1os en la gesti\u00f3n eficaz de los recursos h\u00eddricos compartidos, mismo que, inspirado en el Pacto de la Cuenca del R\u00edo Delaware, ofrece una gu\u00eda pr\u00e1ctica para la implementaci\u00f3n. de est\u00e1ndares de calidad del agua, esenciales para la sostenibilidad de los recursos transfronterizos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El art\u00edculo aborda una amplia variedad de temas cruciales para la planificaci\u00f3n y administraci\u00f3n de recursos h\u00eddricos, tales como:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Administraci\u00f3n y Gesti\u00f3n del Agua<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Calidad y Asignaci\u00f3n de Recursos H\u00eddricos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Financiamiento y Distribuci\u00f3n de Costos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Resoluci\u00f3n de Disputas y Conflictos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Intercambio de Datos y Colaboraci\u00f3n Internacional<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, incluye ap\u00e9ndices que proporcionan directrices detalladas para el desarrollo de planes de gesti\u00f3n y la definici\u00f3n de est\u00e1ndares y criterios de calidad del agua. Cuenta con definiciones claras de t\u00e9rminos clave y la delineaci\u00f3n de roles y procesos, por lo que los est\u00e1ndares son adaptables a cualquier escenario de gesti\u00f3n de recursos h\u00eddricos compartidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ASCE 33-23 es una referencia de alto valor para ingenieros ambientales, ingenieros de infraestructura y profesionales involucrados en la gobernanza del agua, la sostenibilidad, la geopol\u00edtica y otras disciplinas relacionadas con la gesti\u00f3n de aguas transfronterizas. Ofrece soluciones pr\u00e1cticas y conocimientos integrales para enfrentar los desaf\u00edos asociados a la gesti\u00f3n de recursos h\u00eddricos m\u00e1s all\u00e1 de las fronteras nacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Foro Permanente de Aguas Binacionales extiende una invitaci\u00f3n a profundizar en el contenido de este documento para obtener una comprensi\u00f3n m\u00e1s amplia y pr\u00e1ctica de las estrategias y enfoques recomendados para la gesti\u00f3n sostenible de los recursos h\u00eddricos compartidos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento puede ser adquirido a trav\u00e9s de <a href=\"https:\/\/ascelibrary.org\/doi\/abs\/10.1061\/9780784414989.bm\">esta liga<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Profesionales del sector h\u00eddrico pueden consultar el documento Acuerdo Integral de Gesti\u00f3n de la Calidad del Agua Transfronteriza con Directrices para el Desarrollo de un Plan de Gesti\u00f3n, Est\u00e1ndares y Criterios, ANSI\/ASCE\/EWRI 33-23.<\/p>","protected":false},"author":221,"featured_media":9884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[36],"tags":[187,186,122],"class_list":["post-9883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-agua-fronteriza","tag-calidad-del-agua","tag-gestion-del-agua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesti\u00f3n de recursos h\u00eddricos: est\u00e1ndares de calidad en la frontera<\/title>\n<meta name=\"description\" content=\"Consulta el documento ANSI\/ASCE\/EWRI 33-23 con directrices clave para la gesti\u00f3n de recursos h\u00eddricos y calidad del agua transfronteriza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.binationalwaters.org\/es\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesti\u00f3n de recursos h\u00eddricos: est\u00e1ndares de calidad en la frontera\" \/>\n<meta property=\"og:description\" content=\"Consulta el documento ANSI\/ASCE\/EWRI 33-23 con directrices clave para la gesti\u00f3n de recursos h\u00eddricos y calidad del agua transfronteriza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.binationalwaters.org\/es\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/\" \/>\n<meta property=\"og:site_name\" content=\"Binational Waters\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100064300953017&amp;mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-08T00:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T18:43:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/06\/mapa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Castro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/\"},\"author\":{\"name\":\"Marco Castro\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#\\\/schema\\\/person\\\/111a16e137a1125ee6293e0c6f5f63ae\"},\"headline\":\"Publican art\u00edculo sobre est\u00e1ndares de calidad del agua fronteriza en la gesti\u00f3n de recursos h\u00eddricos\",\"datePublished\":\"2024-06-08T00:18:44+00:00\",\"dateModified\":\"2025-05-07T18:43:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/\"},\"wordCount\":434,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.binationalwaters.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mapa.jpg\",\"keywords\":[\"agua fronteriza\",\"calidad del agua\",\"Gesti\u00f3n del Agua\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/\",\"url\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/\",\"name\":\"Gesti\u00f3n de recursos h\u00eddricos: est\u00e1ndares de calidad en la frontera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.binationalwaters.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mapa.jpg\",\"datePublished\":\"2024-06-08T00:18:44+00:00\",\"dateModified\":\"2025-05-07T18:43:04+00:00\",\"description\":\"Consulta el documento ANSI\\\/ASCE\\\/EWRI 33-23 con directrices clave para la gesti\u00f3n de recursos h\u00eddricos y calidad del agua transfronteriza.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.binationalwaters.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mapa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.binationalwaters.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/mapa.jpg\",\"width\":1500,\"height\":1200,\"caption\":\"gesti\u00f3n de recursos h\u00eddricos\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/\",\"name\":\"Binational Waters\",\"description\":\"Water Unites Us\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#organization\",\"name\":\"Binational Waters\",\"url\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.binationalwaters.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/PFBW_eng.png\",\"contentUrl\":\"https:\\\/\\\/www.binationalwaters.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/PFBW_eng.png\",\"width\":1063,\"height\":334,\"caption\":\"Binational Waters\"},\"image\":{\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100064300953017&mibextid=LQQJ4d\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/#\\\/schema\\\/person\\\/111a16e137a1125ee6293e0c6f5f63ae\",\"name\":\"Marco Castro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.gravatar.com\\\/avatar\\\/1bed90b3e3c5ce32a32d25af3d7832a8?s=96&r=g&d=retro\",\"url\":\"https:\\\/\\\/www.gravatar.com\\\/avatar\\\/1bed90b3e3c5ce32a32d25af3d7832a8?s=96&r=g&d=retro\",\"contentUrl\":\"https:\\\/\\\/www.gravatar.com\\\/avatar\\\/1bed90b3e3c5ce32a32d25af3d7832a8?s=96&r=g&d=retro\",\"caption\":\"Marco Castro\"},\"url\":\"https:\\\/\\\/www.binationalwaters.org\\\/es\\\/author\\\/tulioes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesti\u00f3n de recursos h\u00eddricos: est\u00e1ndares de calidad en la frontera","description":"Consulta el documento ANSI\/ASCE\/EWRI 33-23 con directrices clave para la gesti\u00f3n de recursos h\u00eddricos y calidad del agua transfronteriza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.binationalwaters.org\/es\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/","og_locale":"es_MX","og_type":"article","og_title":"Gesti\u00f3n de recursos h\u00eddricos: est\u00e1ndares de calidad en la frontera","og_description":"Consulta el documento ANSI\/ASCE\/EWRI 33-23 con directrices clave para la gesti\u00f3n de recursos h\u00eddricos y calidad del agua transfronteriza.","og_url":"https:\/\/www.binationalwaters.org\/es\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/","og_site_name":"Binational Waters","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100064300953017&mibextid=LQQJ4d","article_published_time":"2024-06-08T00:18:44+00:00","article_modified_time":"2025-05-07T18:43:04+00:00","og_image":[{"width":1500,"height":1200,"url":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/06\/mapa.jpg","type":"image\/jpeg"}],"author":"Marco Castro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marco Castro","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/#article","isPartOf":{"@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/"},"author":{"name":"Marco Castro","@id":"https:\/\/www.binationalwaters.org\/es\/#\/schema\/person\/111a16e137a1125ee6293e0c6f5f63ae"},"headline":"Publican art\u00edculo sobre est\u00e1ndares de calidad del agua fronteriza en la gesti\u00f3n de recursos h\u00eddricos","datePublished":"2024-06-08T00:18:44+00:00","dateModified":"2025-05-07T18:43:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/"},"wordCount":434,"commentCount":0,"publisher":{"@id":"https:\/\/www.binationalwaters.org\/es\/#organization"},"image":{"@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/06\/mapa.jpg","keywords":["agua fronteriza","calidad del agua","Gesti\u00f3n del Agua"],"articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/","url":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/","name":"Gesti\u00f3n de recursos h\u00eddricos: est\u00e1ndares de calidad en la frontera","isPartOf":{"@id":"https:\/\/www.binationalwaters.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/#primaryimage"},"image":{"@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/06\/mapa.jpg","datePublished":"2024-06-08T00:18:44+00:00","dateModified":"2025-05-07T18:43:04+00:00","description":"Consulta el documento ANSI\/ASCE\/EWRI 33-23 con directrices clave para la gesti\u00f3n de recursos h\u00eddricos y calidad del agua transfronteriza.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.binationalwaters.org\/publican-articulo-sobre-estandares-de-calidad-del-agua-fronteriza-en-la-gestion-de-recursos-hidricos\/#primaryimage","url":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/06\/mapa.jpg","contentUrl":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/06\/mapa.jpg","width":1500,"height":1200,"caption":"gesti\u00f3n de recursos h\u00eddricos"},{"@type":"WebSite","@id":"https:\/\/www.binationalwaters.org\/es\/#website","url":"https:\/\/www.binationalwaters.org\/es\/","name":"Aguas Binacionales","description":"El agua nos une","publisher":{"@id":"https:\/\/www.binationalwaters.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.binationalwaters.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.binationalwaters.org\/es\/#organization","name":"Aguas Binacionales","url":"https:\/\/www.binationalwaters.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.binationalwaters.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/07\/PFBW_eng.png","contentUrl":"https:\/\/www.binationalwaters.org\/wp-content\/uploads\/2024\/07\/PFBW_eng.png","width":1063,"height":334,"caption":"Binational Waters"},"image":{"@id":"https:\/\/www.binationalwaters.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100064300953017&mibextid=LQQJ4d"]},{"@type":"Person","@id":"https:\/\/www.binationalwaters.org\/es\/#\/schema\/person\/111a16e137a1125ee6293e0c6f5f63ae","name":"Marco Castro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gravatar.com\/avatar\/1bed90b3e3c5ce32a32d25af3d7832a8?s=96&r=g&d=retro","url":"https:\/\/www.gravatar.com\/avatar\/1bed90b3e3c5ce32a32d25af3d7832a8?s=96&r=g&d=retro","contentUrl":"https:\/\/www.gravatar.com\/avatar\/1bed90b3e3c5ce32a32d25af3d7832a8?s=96&r=g&d=retro","caption":"Marco Castro"},"url":"https:\/\/www.binationalwaters.org\/es\/author\/tulioes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/posts\/9883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/users\/221"}],"replies":[{"embeddable":true,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/comments?post=9883"}],"version-history":[{"count":1,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/posts\/9883\/revisions"}],"predecessor-version":[{"id":9885,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/posts\/9883\/revisions\/9885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/media\/9884"}],"wp:attachment":[{"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/media?parent=9883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/categories?post=9883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.binationalwaters.org\/es\/wp-json\/wp\/v2\/tags?post=9883"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}